{"id":19287,"date":"2017-10-20T09:00:47","date_gmt":"2017-10-20T07:00:47","guid":{"rendered":"https:\/\/hellocare.com\/?p=19287"},"modified":"2025-12-05T10:10:22","modified_gmt":"2025-12-05T09:10:22","slug":"apnee-du-sommeil","status":"publish","type":"post","link":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/","title":{"rendered":"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p><em>Par Paul Rudelle, Pharmacien<\/em><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-2\"><p><span style=\"font-size: regular;\"><span style=\"font-size: 18px; line-height: 1.6em; letter-spacing: 0px;\"><span class=\"fusion-dropcap dropcap\">L<\/span>\u2019apn\u00e9e du sommeil se traduit par des arr\u00eats involontaires de la respiration, se produisant durant le sommeil. Ces pauses r\u00e9p\u00e9titives durent environ une quinzaine de secondes mais peuvent fortement impacter la vie journali\u00e8re du malade. Cette maladie est dangereuse car m\u00e9connue m\u00eame si elle concerne environ 7% de la population adulte fran\u00e7aise.<\/span><!--more--><\/span><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-no-small-visibility in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"768\" height=\"512\" alt=\"Homme brun allong\u00e9 qui se tient la t\u00eate en regardant son r\u00e9veil\" title=\"apnee du sommeil\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27768%27%20height%3D%27512%27%20viewBox%3D%270%200%20768%20512%27%3E%3Crect%20width%3D%27768%27%20height%3D%27512%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2017\/10\/apnee-du-sommeil.jpg\" class=\"lazyload img-responsive wp-image-23955\"\/><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-top:0px;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:36;line-height:1.25;\"><h2>Comprendre et soigner son apn\u00e9e<\/h2><\/h2><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-top:0px;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-3\"><div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3>Comment la d\u00e9tecter ?<\/h3>\n<p>En r\u00e8gle g\u00e9n\u00e9rale, les personnes qui souffrent d\u2019apn\u00e9e du sommeil\u00a0<b>ne sont pas conscientes<\/b><b>des \u00ab\u00a0pauses\u00a0\u00bb respiratoires<\/b>\u00a0qu\u2019elles font dans la nuit et donc\u00a0<b>inconscientes de leur maladie<\/b>. Pourtant, l\u2019apn\u00e9e du sommeil oblige le cerveau \u00e0 se r\u00e9veiller\u00a0pour retrouver une respiration normale, c\u2019est pourquoi les personnes atteintes sont souvent tr\u00e8s\u00a0<b>fatigu\u00e9es au r\u00e9veil.<\/b><\/p>\n<p>Les sympt\u00f4mes qui peuvent \u00e9voquer qu\u2019une personne est atteinte d\u2019apn\u00e9es du sommeil sont donc li\u00e9s \u00e0 ce repos incomplet ou de mauvaise qualit\u00e9\u00a0:<\/p>\n<ul>\n<li>Une\u00a0<b>fatigue importante<\/b>\u00a0d\u00e8s le r\u00e9veil et tout au long de la journ\u00e9e<\/li>\n<li>Une\u00a0<b>somnolence<\/b>\u00a0et des\u00a0<b>endormissements non contr\u00f4l\u00e9s<\/b><\/li>\n<li>Des\u00a0<b>maux de t\u00eates<\/b>\u00a0au r\u00e9veil<\/li>\n<li>Une difficult\u00e9 \u00e0 se concentrer, des troubles de la m\u00e9moire<\/li>\n<li>Une\u00a0<b>irritabilit\u00e9<\/b>, un\u00a0<b>sentiment d\u00e9pressif<\/b><\/li>\n<\/ul>\n<p><b>La d\u00e9tection<\/b>\u00a0a le plus souvent lieu par le conjoint ou la conjointe durant le sommeil qui note des pauses respiratoires plus ou moins longues se manifestant par l\u2019arr\u00eat de la respiration ou des ronflements pendant quelques secondes.<\/p>\n<p>Pendant la nuit, ces\u00a0<b>ronflements<\/b>\u00a0sont souvent observ\u00e9s lors des apn\u00e9es obstructives. Cependant, le ronflement n\u2019est pas un signe sp\u00e9cifique de l\u2019apn\u00e9e du sommeil. En revanche, il arrive que la personne atteinte ait l\u2019impression de s\u2019\u00e9touffer, de suffoquer pendant la nuit. Il faut alors\u00a0<b>consulter un m\u00e9decin<\/b>\u00a0!<\/p>\n<\/div>\n<\/div>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-4\"><div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 id=\"ui-id-1\" class=\"clearfix eltd-title-holder ui-accordion-header ui-state-default ui-accordion-header-active ui-state-active ui-corner-top ui-state-hover\" tabindex=\"0\" role=\"tab\" aria-controls=\"ui-id-2\" aria-selected=\"true\" aria-expanded=\"true\"><span class=\"eltd-tab-title\"><span class=\"eltd-tab-title-inner\">Les causes de l&rsquo;apn\u00e9e du sommeil<\/span><\/span><\/h3>\n<div id=\"ui-id-2\" class=\"eltd-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-labelledby=\"ui-id-1\" aria-hidden=\"false\">\n<div class=\"eltd-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>La grande majorit\u00e9 des apn\u00e9es du sommeil sont caus\u00e9es par un\u00a0<b>rel\u00e2chement<\/b>\u00a0de certains\u00a0<b>groupes<\/b>\u00a0<b>musculaires<\/b>\u00a0de la sph\u00e8re ORL. Une baisse de la tonicit\u00e9 des muscles de la langue et de la gorge vont venir\u00a0<b>bloquer<\/b><b>partiellement<\/b>\u00a0<b>les<\/b>\u00a0<b>voies<\/b>\u00a0<b>a\u00e9riennes<\/b>, causant une\u00a0<b>respiration<\/b>\u00a0<b>difficile<\/b>\u00a0pour le sujet car le passage de l\u2019air est obstru\u00e9. Cette apn\u00e9e du sommeil est qualifi\u00e9e de\u00a0<b>syndrome d\u2019apn\u00e9e obstructive du sommeil (SAOS).<\/b><\/p>\n<p>De fa\u00e7on plus rare, les apn\u00e9es du sommeil peuvent \u00eatre li\u00e9es \u00e0 un\u00a0<b>trouble neurologique<\/b>. Le cerveau pr\u00e9sente alors un dysfonctionnement et cesse de transmettre des signaux de contraction aux muscles impliqu\u00e9s dans la respiration. Contrairement au SAOS, on parlera ici\u00a0<b>d\u2019apn\u00e9e du sommeil centrale.<\/b><\/p>\n<p>Ces deux cat\u00e9gories d\u2019apn\u00e9es du sommeil ne sont pas totalement exclusives car il arrive souvent que les personnes pr\u00e9sentent une\u00a0<b>apn\u00e9e<\/b>\u00a0<b>du<\/b>\u00a0<b>sommeil<\/b><b>mixte<\/b>, c\u2019est-\u00e0-dire\u00a0<b>obstructive<\/b>\u00a0<b>et<\/b>\u00a0<b>centrale<\/b>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-5\"><div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 id=\"ui-id-3\" class=\"clearfix eltd-title-holder ui-accordion-header ui-state-default ui-accordion-header-active ui-state-active ui-corner-top ui-state-hover\" tabindex=\"0\" role=\"tab\" aria-controls=\"ui-id-4\" aria-selected=\"true\" aria-expanded=\"true\"><span class=\"eltd-tab-title\"><span class=\"eltd-tab-title-inner\">Les risques de maladie<\/span><\/span><\/h3>\n<div id=\"ui-id-4\" class=\"eltd-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-labelledby=\"ui-id-3\" aria-hidden=\"false\">\n<div class=\"eltd-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>A long terme, si l\u2019apn\u00e9e du sommeil n\u2019est pas prise en charge correctement, elle peut entra\u00eener de\u00a0<b>graves<\/b>\u00a0<b>cons\u00e9quences<\/b>\u00a0sur la sant\u00e9 du patient.<\/p>\n<p>Il a \u00e9t\u00e9 prouv\u00e9 que l\u2019apn\u00e9e du sommeil augmentait le risque de d\u00e9velopper par la suite\u00a0<b>des<\/b>\u00a0<b>maladies<\/b>\u00a0<b>cardiovasculaires<\/b>\u00a0comme l\u2019<a href=\"https:\/\/www.hellocare.com\/blog\/hypertension-arterielle\/\" target=\"_blank\" rel=\"noopener noreferrer\">hypertension<\/a>, des infarctus, insuffisance cardiaque, AVC \u2026<br \/>\nLa fatigue intense provoqu\u00e9e par l\u2019apn\u00e9e du sommeil peut \u00eatre un facteur de stress important et induire un \u00e9tat d\u00e9pressif avanc\u00e9 chez la personne atteinte.<br \/>\nLe risque le plus important induit par l\u2019apn\u00e9e du sommeil est celui de s\u2019asphyxier pendant son sommeil.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-6\"><div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3 id=\"ui-id-5\" class=\"clearfix eltd-title-holder ui-accordion-header ui-state-default ui-accordion-header-active ui-state-active ui-corner-top ui-state-hover\" tabindex=\"0\" role=\"tab\" aria-controls=\"ui-id-6\" aria-selected=\"true\" aria-expanded=\"true\"><span class=\"eltd-tab-title\"><span class=\"eltd-tab-title-inner\">La traiter pour revivre<\/span><\/span><\/h3>\n<div id=\"ui-id-6\" class=\"eltd-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-labelledby=\"ui-id-5\" aria-hidden=\"false\">\n<div class=\"eltd-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Si, \u00e0 ce jour, les traitements m\u00e9dicamenteux ne se sont pas r\u00e9v\u00e9l\u00e9s tr\u00e8s efficaces contre l\u2019apn\u00e9e du sommeil, la maladie peut \u00eatre combattue par un\u00a0<b>traitement m\u00e9canique.<\/b><\/p>\n<p>Il s\u2019agit du\u00a0<b>traitement par ventilation \u00e0 pression positive continue (PPC)<\/b>, un appareil insuffle l\u2019air en continu par le nez du malade gr\u00e2ce \u00e0\u00a0<b>un masque sp\u00e9cifique qu\u2019il faudra porter pendant la nuit<\/b>. La pression de l\u2019air insuffl\u00e9 permet de maintenir les voies respiratoires parfaitement d\u00e9gag\u00e9es pour que la\u00a0<b>respiration<\/b>\u00a0puisse se faire\u00a0<b>sans<\/b>\u00a0<b>encombre<\/b>. Il s\u2019agit du traitement le plus efficace, il peut para\u00eetre inconfortable mais il permet de faire dispara\u00eetre assez rapidement les sympt\u00f4mes et d\u2019avoir un r\u00e9el impact positif sur la qualit\u00e9 de vie du patient.<\/p>\n<p>Pour les personnes qui tol\u00e8rent mal l\u2019appareil de PPC, il existe des\u00a0<b>orth\u00e8ses d\u2019avanc\u00e9e mandibulaire (OAM)<\/b>, fabriqu\u00e9s sur mesure et s\u2019apparentant \u00e0 un dispositif de\u00a0<b>goutti\u00e8re<\/b>. Cet\u00a0<b>appareil dentaire<\/b>\u00a0permet un avancement pr\u00e9cis et progressif de la mandibule, d\u00e9gageant ainsi les voies a\u00e9riennes, jusqu\u2019\u00e0 ce qu\u2019une position de confort diminuant les apn\u00e9es soit obtenue. Cet appareil est conseill\u00e9 pour les personnes \u00a0souffrant d\u2019<b>apn\u00e9es l\u00e9g\u00e8res \u00e0 mod\u00e9r\u00e9es<\/b>. C\u2019est un dispositif plus l\u00e9ger et moins contraignant mais reste cependant moins efficace que la ventilation PPC.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:5%;--awb-margin-bottom:5%;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-7\"><p><em><a href=\"https:\/\/www.hellocare.com\" target=\"_blank\" rel=\"noopener noreferrer\">&gt; Trouble du sommeil ou grosse fatigue, parlez \u00e0 un m\u00e9decin sans rdv<\/a><\/em><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-top:0px;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:36;line-height:1.25;\"><h2>Les conseils du pharmacien<\/h2><\/h2><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-top:0px;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"768\" height=\"512\" alt=\"M\u00e9decin devant son ordinateur\" title=\"Conseils du medecin\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27768%27%20height%3D%27512%27%20viewBox%3D%270%200%20768%20512%27%3E%3Crect%20width%3D%27768%27%20height%3D%27512%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2017\/05\/conseils-medecin.jpg\" class=\"lazyload img-responsive wp-image-23604\"\/><\/span><\/div><div class=\"fusion-text fusion-text-8\"><div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Il existe certaines mesures pour la pr\u00e9venir et l\u2019\u00e9viter :&quot;}\" data-sheets-formula=\"=MAJUSCULE(GAUCHE(R&#091;-4&#093;C&#091;0&#093;;1))&amp;STXT(R&#091;-4&#093;C&#091;0&#093;;2;NBCAR(R&#091;-4&#093;C&#091;0&#093;)-1) \">Il existe certaines mesures pour la pr\u00e9venir et l\u2019\u00e9viter :<\/span><\/h3>\n<\/div>\n<\/div>\n<div class=\"vc_empty_space\"><\/div>\n<div class=\"eltd-accordion-holder eltd-accordion eltd-boxed light eltd-accordion-square ui-accordion ui-widget ui-helper-reset\" role=\"tablist\">\n<h4 id=\"ui-id-7\" class=\"clearfix eltd-title-holder ui-accordion-header ui-state-default ui-accordion-header-active ui-state-active ui-corner-top\" tabindex=\"0\" role=\"tab\" aria-controls=\"ui-id-8\" aria-selected=\"true\" aria-expanded=\"true\"><span class=\"eltd-tab-title\"><span class=\"eltd-tab-title-inner\">Dormir en bonne position<\/span><\/span><\/h4>\n<div id=\"ui-id-8\" class=\"eltd-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-labelledby=\"ui-id-7\" aria-hidden=\"false\">\n<div class=\"eltd-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Il est conseill\u00e9 pour des raisons anatomiques de dormir sur le c\u00f4t\u00e9 afin d\u2019\u00e9largir au maximum les voies respiratoires. Sur\u00e9lever l\u00e9g\u00e8rement la t\u00eate du lit peut aussi permettre d\u2019\u00e9viter les apn\u00e9es.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-9\"><h4 id=\"ui-id-9\" class=\"clearfix eltd-title-holder ui-accordion-header ui-state-default ui-accordion-header-active ui-state-active ui-corner-top ui-state-hover\" tabindex=\"0\" role=\"tab\" aria-controls=\"ui-id-10\" aria-selected=\"true\" aria-expanded=\"true\"><span class=\"eltd-tab-title\"><span class=\"eltd-tab-title-inner\">Un mode de vie sain<\/span><\/span><\/h4>\n<div id=\"ui-id-10\" class=\"eltd-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-labelledby=\"ui-id-9\" aria-hidden=\"false\">\n<div class=\"eltd-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Le surpoids favorise le d\u00e9veloppement de l\u2019apn\u00e9e du sommeil \u00e0 cause de la graisse faisant pression sur les voies a\u00e9riennes. Le tabagisme aggrave \u00e9galement les apn\u00e9es car il provoque l\u2019inflammation des voies respiratoires.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:5%;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-10\"><h4 id=\"ui-id-11\" class=\"clearfix eltd-title-holder ui-accordion-header ui-state-default ui-accordion-header-active ui-state-active ui-corner-top ui-state-hover\" tabindex=\"0\" role=\"tab\" aria-controls=\"ui-id-12\" aria-selected=\"true\" aria-expanded=\"true\"><span class=\"eltd-tab-title\"><span class=\"eltd-tab-title-inner\">Savoir rep\u00e9rer une apn\u00e9e<\/span><\/span><\/h4>\n<div id=\"ui-id-12\" class=\"eltd-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-labelledby=\"ui-id-11\" aria-hidden=\"false\">\n<div class=\"eltd-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Le patient \u00e9tant tr\u00e8s souvent inconscient des \u00e9pisodes apn\u00e9iques, c\u2019est au conjoint d\u2019\u00eatre \u00e0 l\u2019aff\u00fbt des sympt\u00f4mes \u00e9voqu\u00e9s plus haut afin d\u2019inciter la personne malade \u00e0 consulter un m\u00e9decin au plus vite\u00a0!<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/www.hellocare.com\/\" target=\"_blank\" aria-label=\"consultation-medecin-en-ligne-hellocare\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"768\" height=\"334\" alt=\"consulter un medecin en ligne hellocare\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27768%27%20height%3D%27334%27%20viewBox%3D%270%200%20768%20334%27%3E%3Crect%20width%3D%27768%27%20height%3D%27334%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2019\/06\/consultation-medecin-en-ligne-hellocare-1.jpg\" class=\"lazyload img-responsive wp-image-23483\"\/><\/a><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2019apn\u00e9e du sommeil se traduit par des arr\u00eats involontaires de la respiration, se produisant durant le sommeil. Ces<\/p>\n","protected":false},"author":28,"featured_media":23955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[575],"tags":[],"class_list":["post-19287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante-generale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?<\/title>\n<meta name=\"description\" content=\"Une apn\u00e9e du sommeil se traduit par des arr\u00eats involontaires de la respiration, se produisant durant le sommeil. Retrouvez nos explications et solutions\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/\" \/>\n<meta property=\"og:site_name\" content=\"Hellocare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hellocareapp\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-20T07:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-05T09:10:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2017\/10\/apnee-du-sommeil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hellocare\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hellocareapp\" \/>\n<meta name=\"twitter:site\" content=\"@hellocareapp\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hellocare\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/\"},\"author\":{\"name\":\"Hellocare\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/person\\\/8492c523f1a5dfe64a4cd21d019a9d1b\"},\"headline\":\"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?\",\"datePublished\":\"2017-10-20T07:00:47+00:00\",\"dateModified\":\"2025-12-05T09:10:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/\"},\"wordCount\":3373,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/apnee-du-sommeil.jpg\",\"articleSection\":[\"Sant\u00e9 g\u00e9n\u00e9rale\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/\",\"name\":\"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/apnee-du-sommeil.jpg\",\"datePublished\":\"2017-10-20T07:00:47+00:00\",\"dateModified\":\"2025-12-05T09:10:22+00:00\",\"description\":\"Une apn\u00e9e du sommeil se traduit par des arr\u00eats involontaires de la respiration, se produisant durant le sommeil. Retrouvez nos explications et solutions\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/apnee-du-sommeil.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/apnee-du-sommeil.jpg\",\"width\":768,\"height\":512,\"caption\":\"Homme brun allong\u00e9 qui se tient la t\u00eate en regardant son r\u00e9veil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/apnee-du-sommeil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/\",\"name\":\"Hellocare\",\"description\":\"T\u00e9l\u00e9consultation et M\u00e9decin en ligne\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#organization\",\"name\":\"Hellocare\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_hellocare.png\",\"contentUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_hellocare.png\",\"width\":537,\"height\":431,\"caption\":\"Hellocare\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hellocareapp\\\/\",\"https:\\\/\\\/x.com\\\/hellocareapp\",\"https:\\\/\\\/www.instagram.com\\\/hellocareapp\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hellocare---health-care-everywhere\"],\"description\":\"Sur Hellocare vous pouvez consulter des m\u00e9decins g\u00e9n\u00e9ralistes, des sp\u00e9cialistes ou des th\u00e9rapeutes disponibles pour tous, et rapidement !\",\"email\":\"hello@hellocare.com\",\"telephone\":\"04 85 80 00 23\",\"legalName\":\"Hellocare SAS\",\"foundingDate\":\"2016-06-24\",\"vatID\":\"FR68821232121\",\"taxID\":\"82123212100045\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/person\\\/8492c523f1a5dfe64a4cd21d019a9d1b\",\"name\":\"Hellocare\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo_hellocare.png\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo_hellocare.png\",\"contentUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo_hellocare.png\",\"caption\":\"Hellocare\"},\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/author\\\/hellocare\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?","description":"Une apn\u00e9e du sommeil se traduit par des arr\u00eats involontaires de la respiration, se produisant durant le sommeil. Retrouvez nos explications et solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/","og_locale":"fr_FR","og_type":"article","og_title":"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?","og_url":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/","og_site_name":"Hellocare","article_publisher":"https:\/\/www.facebook.com\/hellocareapp\/","article_published_time":"2017-10-20T07:00:47+00:00","article_modified_time":"2025-12-05T09:10:22+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2017\/10\/apnee-du-sommeil.jpg","type":"image\/jpeg"}],"author":"Hellocare","twitter_card":"summary_large_image","twitter_creator":"@hellocareapp","twitter_site":"@hellocareapp","twitter_misc":{"\u00c9crit par":"Hellocare","Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/#article","isPartOf":{"@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/"},"author":{"name":"Hellocare","@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/person\/8492c523f1a5dfe64a4cd21d019a9d1b"},"headline":"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?","datePublished":"2017-10-20T07:00:47+00:00","dateModified":"2025-12-05T09:10:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/"},"wordCount":3373,"publisher":{"@id":"https:\/\/www.hellocare.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2017\/10\/apnee-du-sommeil.jpg","articleSection":["Sant\u00e9 g\u00e9n\u00e9rale"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/","url":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/","name":"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?","isPartOf":{"@id":"https:\/\/www.hellocare.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/#primaryimage"},"image":{"@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2017\/10\/apnee-du-sommeil.jpg","datePublished":"2017-10-20T07:00:47+00:00","dateModified":"2025-12-05T09:10:22+00:00","description":"Une apn\u00e9e du sommeil se traduit par des arr\u00eats involontaires de la respiration, se produisant durant le sommeil. Retrouvez nos explications et solutions","breadcrumb":{"@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/#primaryimage","url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2017\/10\/apnee-du-sommeil.jpg","contentUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2017\/10\/apnee-du-sommeil.jpg","width":768,"height":512,"caption":"Homme brun allong\u00e9 qui se tient la t\u00eate en regardant son r\u00e9veil"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hellocare.com\/blog\/apnee-du-sommeil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hellocare.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Apn\u00e9e du sommeil : Vos nuits g\u00e2chent vos journ\u00e9es ?"}]},{"@type":"WebSite","@id":"https:\/\/www.hellocare.com\/blog\/#website","url":"https:\/\/www.hellocare.com\/blog\/","name":"Hellocare","description":"T\u00e9l\u00e9consultation et M\u00e9decin en ligne","publisher":{"@id":"https:\/\/www.hellocare.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hellocare.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.hellocare.com\/blog\/#organization","name":"Hellocare","url":"https:\/\/www.hellocare.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2020\/04\/Logo_hellocare.png","contentUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2020\/04\/Logo_hellocare.png","width":537,"height":431,"caption":"Hellocare"},"image":{"@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hellocareapp\/","https:\/\/x.com\/hellocareapp","https:\/\/www.instagram.com\/hellocareapp","https:\/\/www.linkedin.com\/company\/hellocare---health-care-everywhere"],"description":"Sur Hellocare vous pouvez consulter des m\u00e9decins g\u00e9n\u00e9ralistes, des sp\u00e9cialistes ou des th\u00e9rapeutes disponibles pour tous, et rapidement !","email":"hello@hellocare.com","telephone":"04 85 80 00 23","legalName":"Hellocare SAS","foundingDate":"2016-06-24","vatID":"FR68821232121","taxID":"82123212100045"},{"@type":"Person","@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/person\/8492c523f1a5dfe64a4cd21d019a9d1b","name":"Hellocare","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2026\/01\/Logo_hellocare.png","url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2026\/01\/Logo_hellocare.png","contentUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2026\/01\/Logo_hellocare.png","caption":"Hellocare"},"url":"https:\/\/www.hellocare.com\/blog\/author\/hellocare\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts\/19287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/comments?post=19287"}],"version-history":[{"count":2,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts\/19287\/revisions"}],"predecessor-version":[{"id":37006,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts\/19287\/revisions\/37006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/media\/23955"}],"wp:attachment":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/media?parent=19287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/categories?post=19287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/tags?post=19287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}