{"id":28402,"date":"2021-02-02T17:19:56","date_gmt":"2021-02-02T16:19:56","guid":{"rendered":"https:\/\/hellocare.com\/blog\/?p=28402"},"modified":"2025-12-05T10:14:12","modified_gmt":"2025-12-05T09:14:12","slug":"fausse-couche-symptomes","status":"publish","type":"post","link":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/","title":{"rendered":"Fausse couche : comment reconna\u00eetre les sympt\u00f4mes ?"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-1 content-boxes-clean-vertical content-left content-boxes-icon-on-top\" style=\"--awb-backgroundcolor:#f3f6f7;--awb-body-color:#1f1f1f;--awb-title-color:#1f1f1f;--awb-iconcolor:#ffffff;--awb-hover-accent-color:#3bb2b8;--awb-circle-hover-accent-color:#3bb2b8;--awb-item-margin-bottom:40px;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:#f3f6f7;--awb-iconcolor:#ffffff;border-color:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper-background link-area-link-icon link-type-button icon-hover-animation-pulsate\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"https:\/\/www.hellocare.com\/\" target=\"_self\"><div class=\"icon\"><i style=\"border-color:rgba(77,57,233,0);border-width:0px;background-color:#3bb2b8;box-sizing:content-box;height:48px;width:48px;line-height:48px;border-radius:100%;font-size:24px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-video fas circle-yes\"><\/i><\/div><h2 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h2_typography-font-size:24px;--fontSize:24;line-height:1.25;\">Des m\u00e9decins g\u00e9n\u00e9ralistes et sp\u00e9cialistes en t\u00e9l\u00e9consultation 7j\/7<\/h2><\/a><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<p>M\u00e9decins g\u00e9n\u00e9ralistes et sp\u00e9cialistes disponibles pour des consultations en vid\u00e9o s\u00e9curis\u00e9es.<br \/>\nRemboursable par l\u2019Assurance Maladie.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><a class=\"fusion-read-more-button fusion-content-box-button fusion-button button-default fusion-button-default-size button- button-flat\" href=\"https:\/\/www.hellocare.com\/\" target=\"_self\"><span class=\"fusion-button-text\">PRENDRE RDV<\/span><\/a><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p><span style=\"font-size: regular;\"><span style=\"font-size: 18px; line-height: 1.6em; letter-spacing: 0px;\"><span class=\"fusion-dropcap dropcap\">S<\/span><span style=\"font-weight: 400;\">i la joie d\u2019attendre un b\u00e9b\u00e9 est grande, la grossesse s\u2019accompagne aussi de nombreuses craintes. La peur de faire une fausse couche, notamment, occupe l\u2019esprit de nombreuses mamans. Surtout durant le premier trimestre\u00a0! C\u2019est en effet l\u00e0 que le risque est maximal, bien qu\u2019il existe des cas plus tardifs\u2026 Mais s\u2019il est conseill\u00e9 de rester vigilante, il ne faut pas non plus vivre dans l\u2019angoisse\u00a0! Gardez \u00e0 l\u2019esprit que la plupart des sensations \u00ab\u00a0curieuses\u00a0\u00bb et des changements corporels que vous observerez sont tout \u00e0 fait naturels. Mais alors, quand faut-il consulter\u00a0? Pour vous aider \u00e0 y voir plus clair, nous d\u00e9taillons chaque sympt\u00f4me de fausse couche potentiel. \u00a0 <\/span><\/span><!--more--><\/span><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:500px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"200\" alt=\"Sympt\u00f4mes fausse couche\" title=\"fausse couche\" src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me.jpg\" data-orig-src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me.jpg\" class=\"lazyload img-responsive wp-image-28405\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27768%27%20height%3D%27512%27%20viewBox%3D%270%200%20768%20512%27%3E%3Crect%20width%3D%27768%27%20height%3D%27512%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me-200x133.jpg 200w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me-400x267.jpg 400w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me-600x400.jpg 600w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me.jpg 768w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me-800x533.jpg 800w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1000px) 100vw, 300px\" \/><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2><span style=\"font-weight: 400;\">Sympt\u00f4me fausse couche : des saignements anormaux<\/span><\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-2\"><p>Premi\u00e8re chose \u00e0 savoir : de nombreuses femmes enceintes pr\u00e9sentent des saignements sans gravit\u00e9 durant le premier trimestre. On peut citer le \u00ab spotting \u00bb par exemple (\u00ab tache \u00bb en fran\u00e7ais). Ces petites pertes rouges \u00e0 marrons proviennent simplement du col de l\u2019ut\u00e9rus, fragilis\u00e9 durant la grossesse\u2026 M\u00eame s\u2019il est toujours recommand\u00e9 de les signaler \u00e0 votre m\u00e9decin par pr\u00e9caution !<\/p>\n<p>Cela \u00e9tant dit, <strong>ce sont surtout les saignements tr\u00e8s abondants et\/ou continus qui doivent vous pousser \u00e0 consulter rapidement<\/strong>. A plus forte raison s\u2019ils sont de couleur noir\u00e2tre et qu\u2019ils contiennent des caillots ou des mati\u00e8res brun\u00e2tres !<\/p>\n<p>Ayez aussi le r\u00e9flexe de consulter pour <strong>TOUT<\/strong> saignement survenant durant le 2nd et le 3\u00e8me trimestre. A ce stade ce n\u2019est pas forc\u00e9ment un signe de fausse couche. Mais ils peuvent r\u00e9v\u00e9ler d\u2019autres soucis comme un risque d\u2019<a href=\"https:\/\/www.hellocare.com\/blog\/premature-precautions-bebe\/\" target=\"_blank\" rel=\"noopener noreferrer\">accouchement pr\u00e9matur\u00e9<\/a> par exemple.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-3\"><blockquote>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: large;\"><a href=\"https:\/\/www.hellocare.com\/\" rel=\"noopener noreferrer\">Vous pensez avoir un les sympt\u00f4mes d&rsquo;une fausse couche ?<br \/>\nConsultez rapidement en ligne\u00a0\u00a0<i class=\"fas fa-video\"><\/i> <\/a>\u00a0<\/span><\/strong><\/p>\n<\/blockquote>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2><span style=\"font-weight: 400;\">Comment reconna\u00eetre les douleurs suspectes<\/span><\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-4\"><p>Il est tout \u00e0 fait naturel de souffrir de petites crampes abdominales en d\u00e9but de grossesse. Ou encore de sensations de tiraillement dans le bas-ventre. Vous pouvez aussi avoir un peu mal au dos d\u00e8s le premier trimestre\u2026 <strong>Ce qui n\u2019est pas naturel en revanche, c\u2019est de souffrir de douleurs abdominales s\u00e9v\u00e8res \u2013 ressemblant \u00e0 de vraies contractions \u2013 ou d\u2019intenses douleurs dorsales durant les premiers mois de grossesse<\/strong>.<\/p>\n<p>Dans le doute, mieux vaut consulter en urgence. Surtout si vos douleurs s\u2019accompagnent d\u2019autres sympt\u00f4mes comme des saignements ou des vomissements !<\/p>\n<p>Mais gardez \u00e0 l\u2019esprit que vous ne faites pas forc\u00e9ment une fausse couche. En effet, de nombreuses pathologies peuvent \u00eatre en cause comme une <a href=\"https:\/\/www.hellocare.com\/blog\/comment-reconnaitre-symptome-appendicite\/\" target=\"_blank\" rel=\"noopener noreferrer\">appendicite<\/a> par exemple. Dans ce cas il est g\u00e9n\u00e9ralement possible d\u2019intervenir tout en pr\u00e9servant b\u00e9b\u00e9 !<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2><span style=\"font-weight: 400;\">Autre sympt\u00f4me : la disparition des signes de grossesse<\/span><\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-5\"><p>Seins tendus, naus\u00e9es, sautes d\u2019humeur\u2026 Ces <a href=\"https:\/\/www.hellocare.com\/blog\/signes-de-grossesse\/\" target=\"_blank\" rel=\"noopener noreferrer\">signes de grossesse<\/a> sont pr\u00e9sents chez de nombreuses femmes enceintes durant le premier trimestre. G\u00e9n\u00e9ralement, ils s\u2019estompent progressivement au fil du temps. Au point que certains d\u2019entre eux disparaissent totalement vers le d\u00e9but du second trimestre ! Mais ce n\u2019est pas syst\u00e9matique. Leur \u00e9volution varie en effet d\u2019une femme \u00e0 l\u2019autre.<\/p>\n<p>Vos naus\u00e9es peuvent ainsi vous \u00e9pargner pendant 3 jours par exemple avant de \u00ab revenir \u00e0 la charge \u00bb. Cela n\u2019a rien d\u2019anormal ! En revanche, <strong>une disparition brutale de TOUS vos signes de grossesse est assez suspecte durant le premier trimestre<\/strong>. Il peut s\u2019agir d\u2019un sympt\u00f4me de fausse couche\u2026 Ou non. Par pr\u00e9caution, il est recommand\u00e9 de consulter. Et ce, m\u00eame si vous ne constatez ni saignement ni douleur particuli\u00e8re.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2><span style=\"font-weight: 400;\">La fausse couche h\u00e9morragique<\/span><\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-6\"><p>Dans la grande majorit\u00e9 des cas, une fausse couche spontan\u00e9e ne pr\u00e9sente aucun danger pour la maman. Cependant, elle s\u2019accompagne parfois d\u2019une h\u00e9morragie importante. <strong>Les signes qui doivent vous alerter : des saignements abondants refusant de s\u2019arr\u00eater associ\u00e9s \u00e0 des sympt\u00f4mes de choc h\u00e9morragique<\/strong>. Ceux-ci peuvent varier selon les cas mais ils comprennent g\u00e9n\u00e9ralement :<\/p>\n<ul>\n<li>de la p\u00e2leur ;<\/li>\n<li>des \u00e9tourdissement et des vertiges ;<\/li>\n<li>de la confusion ;<\/li>\n<li>une grande sensation de faiblesse ou fatigue ;<\/li>\n<li>des naus\u00e9es et\/ou vomissements ;<\/li>\n<li>des variations soudaines de temp\u00e9rature ;<\/li>\n<li>une acc\u00e9l\u00e9ration du rythme cardiaque (tachycardie).<\/li>\n<\/ul>\n<p>Dans cette situation, appelez les urgences ! Une intervention chirurgicale est souvent n\u00e9cessaire pour stopper l\u2019h\u00e9morragie.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2><span style=\"font-weight: 400;\">Comment \u00eatre s\u00fbre qu\u2019il s\u2019agit bien d\u2019une fausse couche\u00a0?<\/span><\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-7\"><p>Comme vous avez pu le constater, les sympt\u00f4mes de fausse couche ne sont pas toujours tr\u00e8s \u00ab clairs \u00bb. C\u2019est pourquoi <strong>seuls des examens permettent vraiment de savoir si votre grossesse se poursuit ou non<\/strong>. Si les analyses de sang donnent d\u00e9j\u00e0 des \u00e9l\u00e9ments de r\u00e9ponse, l\u2019\u00e9chographie reste l\u2019examen de r\u00e9f\u00e9rence. D\u2019ailleurs, il arrive que cette derni\u00e8re r\u00e9v\u00e8le une fausse couche lors du <a href=\"https:\/\/www.hellocare.com\/blog\/calendrier-de-grossesse\/\" target=\"_blank\" rel=\"noopener noreferrer\">suivi de grossesse<\/a>, alors qu\u2019il n\u2019y avait pas le moindre signe annonciateur\u2026 Mais quelles que soient les circonstances, cette \u00e9tape est toujours traumatisante pour les couples.<\/p>\n<p>Au besoin, faites donc appel \u00e0 un sp\u00e9cialiste pour mieux <a href=\"https:\/\/www.hellocare.com\/blog\/fausse-couche-arret-de-grossesse\/\" target=\"_blank\" rel=\"noopener noreferrer\">g\u00e9rer votre arr\u00eat de grossesse<\/a>. Et surtout ne perdez pas espoir ! Gardez \u00e0 l\u2019esprit que la plupart des fausses couches sont li\u00e9es \u00e0 des \u00e9v\u00e9nements isol\u00e9s comme une anomalie chromosomique. Ou encore une infection comme une grippe s\u00e9v\u00e8re par exemple (d\u2019o\u00f9 l\u2019int\u00e9r\u00eat d\u2019\u00eatre <a href=\"https:\/\/www.hellocare.com\/blog\/vaccination-antigrippale-grossesse\/\" target=\"_blank\" rel=\"noopener noreferrer\">vaccin\u00e9e durant votre grossesse<\/a>). En d\u2019autres termes, il y a de grandes chances que vous puissiez mener votre prochaine grossesse sans probl\u00e8me !<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/www.hellocare.com\/\" target=\"_blank\" aria-label=\"consulter m\u00e9decins en ligne\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"300\" height=\"130\" alt=\"consulter m\u00e9decin en ligne\" src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2019\/03\/CTA_ge\u0301ne\u0301ralistes_spe\u0301cialites-.png\" data-orig-src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2019\/03\/CTA_ge\u0301ne\u0301ralistes_spe\u0301cialites-.png\" class=\"lazyload img-responsive wp-image-27447\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27768%27%20height%3D%27334%27%20viewBox%3D%270%200%20768%20334%27%3E%3Crect%20width%3D%27768%27%20height%3D%27334%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2019\/03\/CTA_ge\u0301ne\u0301ralistes_spe\u0301cialites--200x87.png 200w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2019\/03\/CTA_ge\u0301ne\u0301ralistes_spe\u0301cialites--400x174.png 400w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2019\/03\/CTA_ge\u0301ne\u0301ralistes_spe\u0301cialites--600x261.png 600w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2019\/03\/CTA_ge\u0301ne\u0301ralistes_spe\u0301cialites-.png 768w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2019\/03\/CTA_ge\u0301ne\u0301ralistes_spe\u0301cialites--800x348.png 800w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2019\/03\/CTA_ge\u0301ne\u0301ralistes_spe\u0301cialites--1200x522.png 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1000px) 100vw, 300px\" \/><\/a><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>i la joie d\u2019attendre un b\u00e9b\u00e9 est grande, la grossesse s\u2019accompagne aussi de nombreuses craintes. La peur de<\/p>\n","protected":false},"author":21,"featured_media":28405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[575],"tags":[],"class_list":["post-28402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante-generale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reconna\u00eetre les sympt\u00f4mes d&#039;une fausse couche | Hellocare<\/title>\n<meta name=\"description\" content=\"Saignements anormaux, douleurs suspecte... Pour vous aider \u00e0 y voir plus clair, nous d\u00e9taillons chaque sympt\u00f4me de fausse couche potentiel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fausse couche : comment reconna\u00eetre les sympt\u00f4mes ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/\" \/>\n<meta property=\"og:site_name\" content=\"Hellocare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hellocareapp\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-02T16:19:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-05T09:14:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"joanna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hellocareapp\" \/>\n<meta name=\"twitter:site\" content=\"@hellocareapp\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"joanna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/\"},\"author\":{\"name\":\"joanna\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/person\\\/955d44848b20953ea8c7c8b21fbe2a39\"},\"headline\":\"Fausse couche : comment reconna\u00eetre les sympt\u00f4mes ?\",\"datePublished\":\"2021-02-02T16:19:56+00:00\",\"dateModified\":\"2025-12-05T09:14:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/\"},\"wordCount\":3649,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Fausse-couche-sympto\u0302me.jpg\",\"articleSection\":[\"Sant\u00e9 g\u00e9n\u00e9rale\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/\",\"name\":\"Reconna\u00eetre les sympt\u00f4mes d'une fausse couche | Hellocare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Fausse-couche-sympto\u0302me.jpg\",\"datePublished\":\"2021-02-02T16:19:56+00:00\",\"dateModified\":\"2025-12-05T09:14:12+00:00\",\"description\":\"Saignements anormaux, douleurs suspecte... Pour vous aider \u00e0 y voir plus clair, nous d\u00e9taillons chaque sympt\u00f4me de fausse couche potentiel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Fausse-couche-sympto\u0302me.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Fausse-couche-sympto\u0302me.jpg\",\"width\":768,\"height\":512,\"caption\":\"Sympt\u00f4mes fausse couche\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/fausse-couche-symptomes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fausse couche : comment reconna\u00eetre les sympt\u00f4mes ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/\",\"name\":\"Hellocare\",\"description\":\"T\u00e9l\u00e9consultation et M\u00e9decin en ligne\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#organization\",\"name\":\"Hellocare\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_hellocare.png\",\"contentUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_hellocare.png\",\"width\":537,\"height\":431,\"caption\":\"Hellocare\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hellocareapp\\\/\",\"https:\\\/\\\/x.com\\\/hellocareapp\",\"https:\\\/\\\/www.instagram.com\\\/hellocareapp\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hellocare---health-care-everywhere\"],\"description\":\"Sur Hellocare vous pouvez consulter des m\u00e9decins g\u00e9n\u00e9ralistes, des sp\u00e9cialistes ou des th\u00e9rapeutes disponibles pour tous, et rapidement !\",\"email\":\"hello@hellocare.com\",\"telephone\":\"04 85 80 00 23\",\"legalName\":\"Hellocare SAS\",\"foundingDate\":\"2016-06-24\",\"vatID\":\"FR68821232121\",\"taxID\":\"82123212100045\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/person\\\/955d44848b20953ea8c7c8b21fbe2a39\",\"name\":\"joanna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ne-pas-attraper-de-virus-au-bureau.jpg\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ne-pas-attraper-de-virus-au-bureau.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/ne-pas-attraper-de-virus-au-bureau.jpg\",\"caption\":\"joanna\"},\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/author\\\/joanna\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reconna\u00eetre les sympt\u00f4mes d'une fausse couche | Hellocare","description":"Saignements anormaux, douleurs suspecte... Pour vous aider \u00e0 y voir plus clair, nous d\u00e9taillons chaque sympt\u00f4me de fausse couche potentiel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/","og_locale":"fr_FR","og_type":"article","og_title":"Fausse couche : comment reconna\u00eetre les sympt\u00f4mes ?","og_url":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/","og_site_name":"Hellocare","article_publisher":"https:\/\/www.facebook.com\/hellocareapp\/","article_published_time":"2021-02-02T16:19:56+00:00","article_modified_time":"2025-12-05T09:14:12+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me.jpg","type":"image\/jpeg"}],"author":"joanna","twitter_card":"summary_large_image","twitter_creator":"@hellocareapp","twitter_site":"@hellocareapp","twitter_misc":{"\u00c9crit par":"joanna","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/#article","isPartOf":{"@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/"},"author":{"name":"joanna","@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/person\/955d44848b20953ea8c7c8b21fbe2a39"},"headline":"Fausse couche : comment reconna\u00eetre les sympt\u00f4mes ?","datePublished":"2021-02-02T16:19:56+00:00","dateModified":"2025-12-05T09:14:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/"},"wordCount":3649,"publisher":{"@id":"https:\/\/www.hellocare.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me.jpg","articleSection":["Sant\u00e9 g\u00e9n\u00e9rale"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/","url":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/","name":"Reconna\u00eetre les sympt\u00f4mes d'une fausse couche | Hellocare","isPartOf":{"@id":"https:\/\/www.hellocare.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/#primaryimage"},"image":{"@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me.jpg","datePublished":"2021-02-02T16:19:56+00:00","dateModified":"2025-12-05T09:14:12+00:00","description":"Saignements anormaux, douleurs suspecte... Pour vous aider \u00e0 y voir plus clair, nous d\u00e9taillons chaque sympt\u00f4me de fausse couche potentiel.","breadcrumb":{"@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/#primaryimage","url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me.jpg","contentUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2021\/02\/Fausse-couche-sympto\u0302me.jpg","width":768,"height":512,"caption":"Sympt\u00f4mes fausse couche"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hellocare.com\/blog\/fausse-couche-symptomes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hellocare.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Fausse couche : comment reconna\u00eetre les sympt\u00f4mes ?"}]},{"@type":"WebSite","@id":"https:\/\/www.hellocare.com\/blog\/#website","url":"https:\/\/www.hellocare.com\/blog\/","name":"Hellocare","description":"T\u00e9l\u00e9consultation et M\u00e9decin en ligne","publisher":{"@id":"https:\/\/www.hellocare.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hellocare.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.hellocare.com\/blog\/#organization","name":"Hellocare","url":"https:\/\/www.hellocare.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2020\/04\/Logo_hellocare.png","contentUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2020\/04\/Logo_hellocare.png","width":537,"height":431,"caption":"Hellocare"},"image":{"@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hellocareapp\/","https:\/\/x.com\/hellocareapp","https:\/\/www.instagram.com\/hellocareapp","https:\/\/www.linkedin.com\/company\/hellocare---health-care-everywhere"],"description":"Sur Hellocare vous pouvez consulter des m\u00e9decins g\u00e9n\u00e9ralistes, des sp\u00e9cialistes ou des th\u00e9rapeutes disponibles pour tous, et rapidement !","email":"hello@hellocare.com","telephone":"04 85 80 00 23","legalName":"Hellocare SAS","foundingDate":"2016-06-24","vatID":"FR68821232121","taxID":"82123212100045"},{"@type":"Person","@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/person\/955d44848b20953ea8c7c8b21fbe2a39","name":"joanna","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2018\/12\/ne-pas-attraper-de-virus-au-bureau.jpg","url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2018\/12\/ne-pas-attraper-de-virus-au-bureau.jpg","contentUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2018\/12\/ne-pas-attraper-de-virus-au-bureau.jpg","caption":"joanna"},"url":"https:\/\/www.hellocare.com\/blog\/author\/joanna\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts\/28402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/comments?post=28402"}],"version-history":[{"count":2,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts\/28402\/revisions"}],"predecessor-version":[{"id":37301,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts\/28402\/revisions\/37301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/media\/28405"}],"wp:attachment":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/media?parent=28402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/categories?post=28402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/tags?post=28402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}