{"id":31524,"date":"2023-04-25T10:30:03","date_gmt":"2023-04-25T08:30:03","guid":{"rendered":"https:\/\/hellocare.com\/blog\/?p=31524"},"modified":"2025-12-08T14:32:40","modified_gmt":"2025-12-08T13:32:40","slug":"douleur-au-cou","status":"publish","type":"post","link":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/","title":{"rendered":"Cervicalgie : comment soulager une douleur au cou ?"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-content-alignment:justify;\"><p><span style=\"font-size: regular;\"><span style=\"font-size: 18px; line-height: 1.6em; letter-spacing: 0px;\"><span class=\"fusion-dropcap dropcap\">Q<\/span>uoi de plus p\u00e9nible qu\u2019une douleur au cou\u00a0? Tr\u00e8s courante, elle peut aussi bien se manifester au r\u00e9veil qu\u2019apr\u00e8s une longue journ\u00e9e de travail\u2026 La bonne nouvelle dans tout \u00e7a c\u2019est que les douleurs cervicales ne cachent rien d\u2019inqui\u00e9tant dans la plupart des cas. Vous pouvez m\u00eame souvent les soulager vous-m\u00eame. Et ce, seulement en l\u2019espace de quelques jours\u00a0! Cependant, certains cas n\u00e9cessitent absolument de voir un m\u00e9decin\u2026 Quelles sont les causes des douleurs au cou\u00a0? Comment les soulager ? Quand devez-vous consulter\u00a0? Nous r\u00e9pondons \u00e0 toute vos questions dans notre article\u00a0!<\/span><\/span><\/p>\n<p><!--more--><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:500px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"800\" height=\"500\" alt=\"Entorse cervicale, torticolis... comment soulager une douleur au cou ?\" title=\"Cervicalgie, torticolis, douleur trap\u00e8ze&#8230; les causes d&rsquo;une douleur au cou et comment la soulager\" src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou.png\" data-orig-src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou.png\" class=\"lazyload img-responsive wp-image-31525\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27800%27%20height%3D%27500%27%20viewBox%3D%270%200%20800%20500%27%3E%3Crect%20width%3D%27800%27%20height%3D%27500%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou-200x125.png 200w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou-400x250.png 400w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou-600x375.png 600w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou.png 800w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1000px) 100vw, 800px\" \/><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2>Quels sont les sympt\u00f4mes d\u2019une cervicalgie\u00a0?<\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-2\"><p>Cervicalgie : un nom savant qui d\u00e9signe tout simplement une douleur situ\u00e9e \u00e0 l\u2019arri\u00e8re du cou. On parle aussi de douleur cervicale ou de douleur \u00e0 la nuque ! Mais quel que soit le nom que vous lui donnez, cette douleur est le principal sympt\u00f4me pr\u00e9sent. Selon la cause de la cervicalgie, elle peut :<\/p>\n<ul>\n<li>appara\u00eetre brusquement, dans la journ\u00e9e ou au r\u00e9veil ;<\/li>\n<li>ou s\u2019installer progressivement.<\/li>\n<\/ul>\n<p>La plupart du temps, elle dispara\u00eet au bout de quelques jours \u00e0 quelques semaines. Mais il en existe des formes chroniques, durant plus de 6 mois ! <strong>A noter \u00e9galement que les douleurs au cou peuvent s\u2019accompagner d\u2019autres sympt\u00f4mes.<\/strong> Les plus courants d\u2019entre eux \u00e9tant :<\/p>\n<ul>\n<li>une douleur au trap\u00e8ze (muscle du haut du dos s\u2019\u00e9tendant jusqu\u2019\u00e0 l\u2019\u00e9paule) ;<\/li>\n<li><a href=\"https:\/\/www.hellocare.com\/blog\/migraine\/\" target=\"_blank\" rel=\"noopener\">des maux de t\u00eate<\/a> ;<\/li>\n<li>de raideurs au cou et une t\u00eate pench\u00e9e sur le c\u00f4t\u00e9 ou en avant, en cas de torticolis ;<\/li>\n<li>des difficult\u00e9s plus ou moins marqu\u00e9es \u00e0 tourner la t\u00eate ;<\/li>\n<li>et\/ou des sensations vertigineuses.<\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-3\"><blockquote>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: large;\"><a href=\"https:\/\/www.hellocare.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Des doutes concernant votre sant\u00e9 ?<br \/>\nPrenez rendez-vous en t\u00e9l\u00e9consultation <i class=\"fas fa-video\"><\/i> <\/a>\u00a0<\/span><\/strong><\/p>\n<\/blockquote>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2>Entorse cervicale, torticolis\u2026 Quelles sont les causes courantes d\u2019une douleur au cou\u00a0?<\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-4\"><p>S\u2019il existe de nombreuses causes possibles aux douleurs au cou, les plus fr\u00e9quentes sont :<\/p>\n<ul>\n<li><strong>le maintien prolong\u00e9 d\u2019une mauvaise position\u2026<\/strong> Durant votre sommeil par exemple ! En effet, c\u2019est g\u00e9n\u00e9ralement parce qu\u2019on s\u2019est \u00ab mal couch\u00e9 \u00bb qu\u2019on se r\u00e9veille avec un mal de cou. On parle alors simplement de cervicalgie posturale. Cela \u00e9tant dit, ce type de douleur peut aussi se manifester si vous \u00eates mal install\u00e9(e) devant votre ordinateur\u2026 Ou si vous tenez trop longtemps votre portable coinc\u00e9 entre votre oreille et votre \u00e9paule par exemple ;<\/li>\n<li><strong>les contractures des muscles du cou.<\/strong> Ce qu\u2019on nomme classiquement un torticolis ! Celui-ci peut aussi \u00eatre d\u00fb \u00e0 une mauvaise position durant votre sommeil. Ou appara\u00eetre si vous tournez trop brusquement la t\u00eate ;<\/li>\n<li><strong>les traumatismes<\/strong> (ex. : accident de voiture, chute durant une activit\u00e9 sportive). En cas de l\u00e9sion des ligaments, cela entra\u00eene une entorse cervicale du type \u00ab coup du lapin \u00bb par exemple ;<\/li>\n<li><strong>un nerf \u00ab coinc\u00e9 \u00bb<\/strong>, notamment en raison d\u2019une <a href=\"https:\/\/www.hellocare.com\/blog\/hernie-types-symptomes\/\" target=\"_blank\" rel=\"noopener\">hernie discale<\/a>. Dans ce cas, la douleur peut irradier jusque dans le bras. On parle alors de n\u00e9vralgie cervicobrachiale.<\/li>\n<li>et<a href=\"https:\/\/www.hellocare.com\/blog\/arthrose-cervicale\/\" target=\"_blank\" rel=\"noopener\"><strong> l\u2019arthrose cervicale<\/strong><\/a> chez les personnes \u00e2g\u00e9es.<\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2>D\u2019autres causes moins courantes de douleur cervicale \u00e0 conna\u00eetre<\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-5\"><p>Plus rarement, une douleur au cou peut aussi r\u00e9v\u00e9ler une maladie plus ou moins grave. On parle alors de \u00ab\u00a0cervicalgie symptomatique\u00a0\u00bb, car cette douleur fait partie des sympt\u00f4mes de la maladie en question. Parmi les diff\u00e9rentes pathologies possibles, citons surtout\u00a0:<\/p>\n<ul>\n<li>diverses maladies infectieuses et\/ou inflammatoires, touchant directement le cou. Comme la spondylarthrite ankylosante par exemple. Il s\u2019agit d\u2019une sorte d\u2019inflammation chronique des articulations. Si elle peut entra\u00eener des douleurs au cou, elle peut aussi engendrer un mal de dos. Ainsi que divers \u00ab enraidissements \u00bb au niveau des poignets, des genoux, etc. A noter \u00e9galement que cette maladie se manifeste par pouss\u00e9es, entrecoup\u00e9es de p\u00e9riodes d\u2019accalmie. <strong>Plus elle est prise en charge rapidement, moins vous risquez de souffrir de complications<\/strong>\u00a0;<\/li>\n<li>parfois la pr\u00e9sence d\u2019une tumeur, dans le cadre d\u2019un cancer du cou par exemple. Mais ce n\u2019est vraiment pas tr\u00e8s courant\u00a0!<\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2>Comment soulager une douleur au cou\u00a0soi-m\u00eame ?<\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-6\"><p>En r\u00e8gle g\u00e9n\u00e9rale, vous pouvez facilement soulager les cervicalgies posturales chez vous. M\u00eame combat pour <a href=\"https:\/\/www.hellocare.com\/blog\/comment-soigner-un-torticolis\/\" target=\"_blank\" rel=\"noopener\">les torticolis les plus \u00ab simples \u00bb<\/a> ! La bonne attitude :<\/p>\n<ul>\n<li>prendre des antidouleurs disponibles sans ordonnance ;<\/li>\n<li>garder votre cou au chaud (ex. : \u00e9charpe ) ;<\/li>\n<li><strong>appliquer des compresses chaudes sur la zone endolorie ;<\/strong><\/li>\n<li>faire des \u00e9tirements \u00ab doux \u00bb et des exercices de relaxation. Vous pouvez m\u00eame <a href=\"https:\/\/www.hellocare.com\/blog\/meditation-de-pleine-conscience-comment-faire\/\" target=\"_blank\" rel=\"noopener\">essayer de m\u00e9diter<\/a> car le stress augmente la douleur !<\/li>\n<\/ul>\n<p>Et pour pr\u00e9venir une autre \u00ab\u00a0crise\u00a0\u00bb\u00a0? Veillez surtout \u00e0 corriger votre posture. Quitte \u00e0 investir dans un oreiller ergonomique par exemple, si vous \u00eates abonn\u00e9(e) au mal de cou au r\u00e9veil\u00a0!<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.3;\"><h2>Douleur cervicale\u00a0: quand consulter\u00a0?<\/h2><\/h3><\/div><div class=\"fusion-text fusion-text-7\"><p>Il est toujours recommand\u00e9 de consulter un m\u00e9decin si :<\/p>\n<ul>\n<li>vos douleurs au cou persistent ou s\u2019aggravent malgr\u00e9 48h \u00e0 72h de \u00ab soins maison \u00bb. A plus forte raison si elles s\u2019accompagnent d\u2019autres sympt\u00f4mes comme des maux de t\u00eate ;<\/li>\n<li>la douleur irradie jusqu\u2019au bras ;<\/li>\n<li><strong>votre douleur cervicale fait suite \u00e0 un choc ou un coup.<\/strong> Normalement il faut consulter imm\u00e9diatement par pr\u00e9caution car cette zone est fragile. Votre blessure date de quelques jours ? Il n\u2019est pas trop tard pour voir un m\u00e9decin ! Dans tous les cas, ne faites pas l\u2019impasse dessus si des sympt\u00f4mes suspects apparaissent (ex. : <a href=\"https:\/\/www.hellocare.com\/blog\/acouphenes-causes-traitements\/\" target=\"_blank\" rel=\"noopener\">acouph\u00e8nes<\/a>, troubles de la vue, pertes de m\u00e9moire) ;<\/li>\n<li>votre douleur s\u2019accompagne d\u2019une forte fi\u00e8vre ;<\/li>\n<li>vous sentez une masse suspecte dans la r\u00e9gion du cou ;<\/li>\n<li>cela fait d\u00e9j\u00e0 plusieurs fois que vous souffrez de douleurs cervicales cette ann\u00e9e.<\/li>\n<\/ul>\n<p>Dans le doute, vous pouvez rapidement <a href=\"https:\/\/www.hellocare.com\" target=\"_blank\" rel=\"noopener\">consulter un m\u00e9decin par visio<\/a> pour vous rassurer\u00a0! Vous devrez peut-\u00eatre passer une radio et d\u2019autres examens pour affiner le diagnostic. Quant au traitement, il d\u00e9pend de la cause de votre douleur. Cependant, sachez qu\u2019il sera m\u00e9dicamenteux dans la plupart des cas. En effet, les op\u00e9rations sont rares\u00a0: elles ne sont employ\u00e9es qu\u2019en cas d\u2019absolue n\u00e9cessit\u00e9\u00a0!<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:500px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/www.hellocare.com\/psychologue\" target=\"_self\" aria-label=\"T\u00e9l\u00e9consultation m\u00e9decin en urgence\"><img decoding=\"async\" width=\"1200\" height=\"627\" alt=\"consulter m\u00e9decin en ligne\" src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2022\/08\/PUB-GENERIQUES-FB-2022-1200-\u00d7-627-px-3.png\" data-orig-src=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2022\/08\/PUB-GENERIQUES-FB-2022-1200-\u00d7-627-px-3.png\" class=\"lazyload img-responsive wp-image-31096\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27627%27%20viewBox%3D%270%200%201200%20627%27%3E%3Crect%20width%3D%271200%27%20height%3D%27627%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2022\/08\/PUB-GENERIQUES-FB-2022-1200-\u00d7-627-px-3-200x105.png 200w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2022\/08\/PUB-GENERIQUES-FB-2022-1200-\u00d7-627-px-3-400x209.png 400w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2022\/08\/PUB-GENERIQUES-FB-2022-1200-\u00d7-627-px-3-600x314.png 600w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2022\/08\/PUB-GENERIQUES-FB-2022-1200-\u00d7-627-px-3-800x418.png 800w, https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2022\/08\/PUB-GENERIQUES-FB-2022-1200-\u00d7-627-px-3.png 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1000px) 100vw, 1200px\" \/><\/a><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>uoi de plus p\u00e9nible qu\u2019une douleur au cou\u00a0? Tr\u00e8s courante, elle peut aussi bien se manifester au r\u00e9veil<\/p>\n","protected":false},"author":28,"featured_media":31525,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[575],"tags":[],"class_list":["post-31524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante-generale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Douleur au cou : causes, sympt\u00f4mes et traitements<\/title>\n<meta name=\"description\" content=\"Quoi de plus p\u00e9nible qu\u2019une douleur au cou\u00a0? Point sur les sympt\u00f4mes de la cervicalgie et les m\u00e9thodes pour la soulager.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cervicalgie : comment soulager une douleur au cou ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/\" \/>\n<meta property=\"og:site_name\" content=\"Hellocare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hellocareapp\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-25T08:30:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-08T13:32:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Hellocare\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hellocareapp\" \/>\n<meta name=\"twitter:site\" content=\"@hellocareapp\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hellocare\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/\"},\"author\":{\"name\":\"Hellocare\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/person\\\/8492c523f1a5dfe64a4cd21d019a9d1b\"},\"headline\":\"Cervicalgie : comment soulager une douleur au cou ?\",\"datePublished\":\"2023-04-25T08:30:03+00:00\",\"dateModified\":\"2025-12-08T13:32:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/\"},\"wordCount\":4670,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/douleur-au-cou.png\",\"articleSection\":[\"Sant\u00e9 g\u00e9n\u00e9rale\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/\",\"name\":\"Douleur au cou : causes, sympt\u00f4mes et traitements\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/douleur-au-cou.png\",\"datePublished\":\"2023-04-25T08:30:03+00:00\",\"dateModified\":\"2025-12-08T13:32:40+00:00\",\"description\":\"Quoi de plus p\u00e9nible qu\u2019une douleur au cou\u00a0? Point sur les sympt\u00f4mes de la cervicalgie et les m\u00e9thodes pour la soulager.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/douleur-au-cou.png\",\"contentUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/douleur-au-cou.png\",\"width\":800,\"height\":500,\"caption\":\"Douleur au cou, entorse cervicale, torticolis... comment soulager une douleur au cou ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/douleur-au-cou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cervicalgie : comment soulager une douleur au cou ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/\",\"name\":\"Hellocare\",\"description\":\"T\u00e9l\u00e9consultation et M\u00e9decin en ligne\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#organization\",\"name\":\"Hellocare\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_hellocare.png\",\"contentUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Logo_hellocare.png\",\"width\":537,\"height\":431,\"caption\":\"Hellocare\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hellocareapp\\\/\",\"https:\\\/\\\/x.com\\\/hellocareapp\",\"https:\\\/\\\/www.instagram.com\\\/hellocareapp\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hellocare---health-care-everywhere\"],\"description\":\"Sur Hellocare vous pouvez consulter des m\u00e9decins g\u00e9n\u00e9ralistes, des sp\u00e9cialistes ou des th\u00e9rapeutes disponibles pour tous, et rapidement !\",\"email\":\"hello@hellocare.com\",\"telephone\":\"04 85 80 00 23\",\"legalName\":\"Hellocare SAS\",\"foundingDate\":\"2016-06-24\",\"vatID\":\"FR68821232121\",\"taxID\":\"82123212100045\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/#\\\/schema\\\/person\\\/8492c523f1a5dfe64a4cd21d019a9d1b\",\"name\":\"Hellocare\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo_hellocare.png\",\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo_hellocare.png\",\"contentUrl\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo_hellocare.png\",\"caption\":\"Hellocare\"},\"url\":\"https:\\\/\\\/www.hellocare.com\\\/blog\\\/author\\\/hellocare\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Douleur au cou : causes, sympt\u00f4mes et traitements","description":"Quoi de plus p\u00e9nible qu\u2019une douleur au cou\u00a0? Point sur les sympt\u00f4mes de la cervicalgie et les m\u00e9thodes pour la soulager.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/","og_locale":"fr_FR","og_type":"article","og_title":"Cervicalgie : comment soulager une douleur au cou ?","og_url":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/","og_site_name":"Hellocare","article_publisher":"https:\/\/www.facebook.com\/hellocareapp\/","article_published_time":"2023-04-25T08:30:03+00:00","article_modified_time":"2025-12-08T13:32:40+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou.png","type":"image\/png"}],"author":"Hellocare","twitter_card":"summary_large_image","twitter_creator":"@hellocareapp","twitter_site":"@hellocareapp","twitter_misc":{"\u00c9crit par":"Hellocare","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/#article","isPartOf":{"@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/"},"author":{"name":"Hellocare","@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/person\/8492c523f1a5dfe64a4cd21d019a9d1b"},"headline":"Cervicalgie : comment soulager une douleur au cou ?","datePublished":"2023-04-25T08:30:03+00:00","dateModified":"2025-12-08T13:32:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/"},"wordCount":4670,"publisher":{"@id":"https:\/\/www.hellocare.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou.png","articleSection":["Sant\u00e9 g\u00e9n\u00e9rale"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/","url":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/","name":"Douleur au cou : causes, sympt\u00f4mes et traitements","isPartOf":{"@id":"https:\/\/www.hellocare.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/#primaryimage"},"image":{"@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou.png","datePublished":"2023-04-25T08:30:03+00:00","dateModified":"2025-12-08T13:32:40+00:00","description":"Quoi de plus p\u00e9nible qu\u2019une douleur au cou\u00a0? Point sur les sympt\u00f4mes de la cervicalgie et les m\u00e9thodes pour la soulager.","breadcrumb":{"@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/#primaryimage","url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou.png","contentUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2023\/04\/douleur-au-cou.png","width":800,"height":500,"caption":"Douleur au cou, entorse cervicale, torticolis... comment soulager une douleur au cou ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hellocare.com\/blog\/douleur-au-cou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hellocare.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cervicalgie : comment soulager une douleur au cou ?"}]},{"@type":"WebSite","@id":"https:\/\/www.hellocare.com\/blog\/#website","url":"https:\/\/www.hellocare.com\/blog\/","name":"Hellocare","description":"T\u00e9l\u00e9consultation et M\u00e9decin en ligne","publisher":{"@id":"https:\/\/www.hellocare.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hellocare.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.hellocare.com\/blog\/#organization","name":"Hellocare","url":"https:\/\/www.hellocare.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2020\/04\/Logo_hellocare.png","contentUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2020\/04\/Logo_hellocare.png","width":537,"height":431,"caption":"Hellocare"},"image":{"@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hellocareapp\/","https:\/\/x.com\/hellocareapp","https:\/\/www.instagram.com\/hellocareapp","https:\/\/www.linkedin.com\/company\/hellocare---health-care-everywhere"],"description":"Sur Hellocare vous pouvez consulter des m\u00e9decins g\u00e9n\u00e9ralistes, des sp\u00e9cialistes ou des th\u00e9rapeutes disponibles pour tous, et rapidement !","email":"hello@hellocare.com","telephone":"04 85 80 00 23","legalName":"Hellocare SAS","foundingDate":"2016-06-24","vatID":"FR68821232121","taxID":"82123212100045"},{"@type":"Person","@id":"https:\/\/www.hellocare.com\/blog\/#\/schema\/person\/8492c523f1a5dfe64a4cd21d019a9d1b","name":"Hellocare","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2026\/01\/Logo_hellocare.png","url":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2026\/01\/Logo_hellocare.png","contentUrl":"https:\/\/www.hellocare.com\/blog\/wp-content\/uploads\/2026\/01\/Logo_hellocare.png","caption":"Hellocare"},"url":"https:\/\/www.hellocare.com\/blog\/author\/hellocare\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts\/31524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/comments?post=31524"}],"version-history":[{"count":3,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts\/31524\/revisions"}],"predecessor-version":[{"id":37460,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/posts\/31524\/revisions\/37460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/media\/31525"}],"wp:attachment":[{"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/media?parent=31524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/categories?post=31524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hellocare.com\/blog\/wp-json\/wp\/v2\/tags?post=31524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}